{"id":20620,"date":"2020-12-03T05:30:00","date_gmt":"2020-12-03T03:30:00","guid":{"rendered":"https:\/\/swat.io\/?p=20620"},"modified":"2026-03-31T12:10:44","modified_gmt":"2026-03-31T10:10:44","slug":"community-management-situationen","status":"publish","type":"post","link":"https:\/\/swat.io\/de\/interaktion\/community-management-situationen\/","title":{"rendered":"8 Tipps und L\u00f6sungen f\u00fcr allt\u00e4gliche Probleme im Community Management"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Wir haben uns an dieser Stelle schon mit strategischen Fragen zum <a href=\"https:\/\/swat.io\/de\/wiki\/community-management\/\" class=\"rank-math-link\">Community Management<\/a>, effizienten Workflows oder Krisenkommunikation besch\u00e4ftigt. Aber was ist mit den <strong>\u201ckleinen\u201d Herausforderungen im Berufsalltag<\/strong>? Wie l\u00e4sst sich in schwierigen Gespr\u00e4chssituationen deeskalieren, was kannst du tun, wenn viele Kommentare au\u00dferhalb der Arbeitszeiten entstehen und wie gehst du als Community ManagerIn mit eigenen Fehlern um?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In diesem Blogpost gehen wir auf solche und andere <strong>typische Situationen im Alltag von Community ManagerInnen<\/strong> ein. Dabei geben wir dir Tipps, wie du Arbeitsabl\u00e4ufe effizienter gestaltest, h\u00e4ufige Probleme l\u00f6st und bei Routineaufgaben einen guten Eindruck hinterl\u00e4sst.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Community Management Tipp #1: Bei komplizierten Fragen Experten kontaktieren<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Manchmal tauchen Fragen in Communities auf, die nur bestimmte Personen in einem Unternehmen oder einer Organisation beantworten k\u00f6nnen. Dann ist es wichtig, <strong>schnell und unkompliziert diese Experten zu erreichen<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Swat.io gibt dir daf\u00fcr verschiedene M\u00f6glichkeiten:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Wenn die Expertin Zugang zu Swat.io hat, weise ihr direkt ein Ticket zu oder tagge sie im <a href=\"https:\/\/help.swat.io\/de\/articles\/12096881-einfuhrung-in-das-aktivitatsprotokoll\" target=\"_blank\" rel=\"noreferrer noopener\">Aktivit\u00e4tsprotokoll<\/a>.\u00a0<\/li>\n\n\n\n<li>Andernfalls gibt es die Option, Kommentare und Tickets aus deiner Ticket-Inbox per E-Mail weiterzuleiten.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Idealerweise <strong>kl\u00e4rt ihr vorab im Team, wer ExpertIn f\u00fcr welches Thema ist.<\/strong> So wissen alle MitarbeiterInnen im <a href=\"https:\/\/swat.io\/de\/lernen\/community-management-guide\/\" target=\"_blank\" data-type=\"URL\" data-id=\"https:\/\/swat.io\/de\/lernen\/community-management-guide\/\" rel=\"noreferrer noopener\">Community Management<\/a> sofort, an wen sie sich wann wenden k\u00f6nnen. Auch der\/die ExpertIn ist dann nicht \u00fcberrascht.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Falls es etwas dauert mit der Antwort, lasse NutzerInnen nicht einfach in der digitalen Warteschleife h\u00e4ngen. Kommentiere \u00f6ffentlich, dass die L\u00f6sung des Problems in Arbeit ist. Schlie\u00dflich erwartet keiner, dass Community ManagerInnen alles wissen.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Community Management Tipp #2: Mit Kommentaren au\u00dferhalb der Arbeitszeiten umgehen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Deine <strong>Community ist sehr aktiv, wenn dein Team Feierabend hat<\/strong>? Dann besteht die Gefahr, dass sich NutzerInnen ignoriert f\u00fchlen, weil sie fr\u00fchestens am n\u00e4chsten Tag eine Reaktion erhalten.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein St\u00fcck weit verhindern l\u00e4sst sich das durch folgende Ma\u00dfnahmen.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>\u00d6ffnungszeiten klar kommunizieren: <\/strong>Mache in den Social-Media-Profilen deines Unternehmens deutlich, wann du und deine KollegInnen arbeiten.&nbsp;<\/li>\n\n\n\n<li><strong>Sofortantworten einrichten: <\/strong>In <a class=\"rank-math-link\" href=\"https:\/\/swat.io\/de\/wiki\/facebook\/\">Facebook<\/a> ist es m\u00f6glich, <a href=\"https:\/\/www.facebook.com\/help\/1615627532020480\" target=\"_blank\" rel=\"noopener\">Sofortantworten<\/a> f\u00fcr bestimmte Zeiten einzurichten. Wenn User dein Unternehmen \u00fcber den Messenger kontaktieren, erhalten sie dann eine automatische Antwort, die zum Beispiel auf die \u00d6ffnungszeiten hinweist.&nbsp;<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1080\" height=\"670\" src=\"https:\/\/swat.io\/wp-content\/uploads\/2020\/12\/community-management-oeffnungszeiten-1080x670.jpg\" alt=\"Community Management \u00d6ffnungszeiten\" class=\"wp-image-20616\" srcset=\"https:\/\/swat.io\/wp-content\/uploads\/2020\/12\/community-management-oeffnungszeiten-1080x670.jpg 1080w, https:\/\/swat.io\/wp-content\/uploads\/2020\/12\/community-management-oeffnungszeiten-750x465.jpg 750w, https:\/\/swat.io\/wp-content\/uploads\/2020\/12\/community-management-oeffnungszeiten-640x397.jpg 640w, https:\/\/swat.io\/wp-content\/uploads\/2020\/12\/community-management-oeffnungszeiten-300x186.jpg 300w, https:\/\/swat.io\/wp-content\/uploads\/2020\/12\/community-management-oeffnungszeiten.jpg 1318w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><figcaption class=\"wp-element-caption\"><em>Klare \u00d6ffnungszeiten zu kommunizieren, beugt falschen Erwartungen vor.<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Auch <strong>Chatbots k\u00f6nnen eine Hilfe im Customer Service <\/strong>beziehungsweise Community Management sein. Sie ersetzen aber nicht den Menschen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Community Management Tipp #3: Konstruktiv mit Feedback umgehen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Feedback von der eigenen Zielgruppe ist wertvoll f\u00fcr Unternehmen. Das gilt auch f\u00fcr negatives Feedback. Allerdings ist Letzteres eine Herausforderung. Wir empfehlen dir, <strong>im Umgang damit Folgendes zu ber\u00fccksichtigen<\/strong>:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ganz wichtig: Reagiere auf jedes Feedback, egal ob positiv oder negativ, und das m\u00f6glichst schnell. Sonst besteht die Gefahr, dass sich NutzerInnen nicht ernst genommen f\u00fchlen oder sich ein Shitstorm entwickelt.&nbsp;<\/li>\n\n\n\n<li>Zeige Usern, dass du ihre Meinung ernst nimmst und sie wertsch\u00e4tzt.&nbsp;<\/li>\n\n\n\n<li>Sei menschlich. Manchmal ist eine Entschuldigung angebracht. Darauf kommen wir noch zur\u00fcck.&nbsp;<\/li>\n\n\n\n<li>Mache deutlich, dass ihr euch im Unternehmen mit dem Feedback befasst.&nbsp;<\/li>\n\n\n\n<li>Biete an, vom \u00f6ffentlichen Kanal auf einen privaten zu wechseln, zum Beispiel dann, wenn Daten ausgetauscht werden oder wenn zus\u00e4tzlicher Gespr\u00e4chsbedarf besteht.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"631\" height=\"312\" src=\"https:\/\/swat.io\/wp-content\/uploads\/2020\/12\/community-management-kanal-wechseln-e1606908505573.jpg\" alt=\"Community Management Kanal wechseln\" class=\"wp-image-20614\" srcset=\"https:\/\/swat.io\/wp-content\/uploads\/2020\/12\/community-management-kanal-wechseln-e1606908505573.jpg 631w, https:\/\/swat.io\/wp-content\/uploads\/2020\/12\/community-management-kanal-wechseln-e1606908505573-300x148.jpg 300w\" sizes=\"(max-width: 631px) 100vw, 631px\" \/><figcaption class=\"wp-element-caption\"><em>Manchmal ist es gut, den Kanal zu wechseln.&nbsp;<\/em><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Community Management Tipp #4: St\u00e4ndig wiederkehrende Fragen beantworten<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wie im Customer Service tauchen <strong>im Community Management vieler Unternehmen immer wieder dieselben Fragen auf<\/strong>. In dieser Situation ist es verlockend, Standardantworten zu verwenden.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Problem dabei: NutzerInnen merken das in der Regel und f\u00fchlen sich nicht wertgesch\u00e4tzt. Versuche deshalb, auf jeden Einzelnen einzugehen. Zeit und M\u00fche sparen kannst du dir durch das <strong>Zurechtlegen von festen Textbausteinen f\u00fcr bestimmte Themen<\/strong>, die du individuell erg\u00e4nzt.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Community Management Tipp #5: Informationen zu Community-Mitgliedern kommunizieren<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wer seine Community-Mitglieder kennt, ist klar im Vorteil. Vor allem, wenn es sich um NutzerInnen handelt, die sich immer wieder zu Wort melden.&nbsp;<br>Swat.io besitzt ein <strong>eigenes <a href=\"https:\/\/swat.io\/de\/wiki\/social-customer-relationship-management\/\" class=\"rank-math-link\">CRM<\/a>, in dem du unter anderem W\u00fcnsche, Bed\u00fcrfnisse und Eigenschaften von Mitgliedern festhalten kannst<\/strong>, ebenso wie Informationen zu bisherigen Interaktionen. So wei\u00dft du oder eine Kollegin sofort, wenn ein User gerne gesiezt werden will, wenn es eine \u201cVorgeschichte\u201d gibt oder wenn es sich um einen Troll handelt.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1080\" height=\"649\" src=\"https:\/\/swat.io\/wp-content\/uploads\/2020\/12\/community-management-crm-swatio-1080x649.png\" alt=\"Community Management CRM Swat.io\" class=\"wp-image-20612\" srcset=\"https:\/\/swat.io\/wp-content\/uploads\/2020\/12\/community-management-crm-swatio-1080x649.png 1080w, https:\/\/swat.io\/wp-content\/uploads\/2020\/12\/community-management-crm-swatio-750x451.png 750w, https:\/\/swat.io\/wp-content\/uploads\/2020\/12\/community-management-crm-swatio-640x385.png 640w, https:\/\/swat.io\/wp-content\/uploads\/2020\/12\/community-management-crm-swatio-300x180.png 300w, https:\/\/swat.io\/wp-content\/uploads\/2020\/12\/community-management-crm-swatio.png 1130w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><figcaption class=\"wp-element-caption\"><em>Ein Blick ins CRM von Swat.io.<\/em><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Community Management Tipp #6: Umgang mit Trollen und Verschw\u00f6rungstheoretikern<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Apropos Trolle: Diesen begegnen wohl alle Community ManagerInnen mindestens einmal in ihrer Karriere.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Doch halt. Wann ist ein Troll eigentlich ein Troll?&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Typische<strong> Anzeichen f\u00fcr einen Troll <\/strong>sind die folgenden:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>NutzerInnen kommentieren hochemotional und mit provokanten \u00c4u\u00dferungen.<\/li>\n\n\n\n<li>Sie gehen nicht auf Versuche zur Probleml\u00f6sung ein.&nbsp;<\/li>\n\n\n\n<li>Sie werden pers\u00f6nlich und beleidigend.&nbsp;<\/li>\n\n\n\n<li>Auffallend leere Profile deuten ebenfalls auf Trolle hin.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Das wichtigste Merkmal von Trollen ist: Ihnen <strong>geht es in erster Linie um Aufmerksamkeit <\/strong>und nicht darum, ein Problem zu l\u00f6sen oder sachliche Kritik vorzubringen.<\/p>\n\n\n\n<div style=\"width:100%;height:0;padding-bottom:79%;position:relative;\"> <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"default\" data-borlabs-cookie-content=\"PGlmcmFtZSBzcmM9Imh0dHBzOi8vZ2lwaHkuY29tL2VtYmVkL0NGMVBlV09BdjY4bGEiIHdpZHRoPSIxMDAlIiBoZWlnaHQ9IjEwMCUiIHN0eWxlPSJwb3NpdGlvbjphYnNvbHV0ZSIgZnJhbWVCb3JkZXI9IjAiIGNsYXNzPSJnaXBoeS1lbWJlZCIgYWxsb3dGdWxsU2NyZWVuPjwvaWZyYW1lPg==\"><div class=\"brlbs-cmpnt-cb-preset-a\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>Standard<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf den Button unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: none\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Weitere Informationen<\/a> <\/div><\/div><\/div><p><a href=\"https:\/\/giphy.com\/gifs\/thanks-making-CF1PeWOAv68la\" target=\"_blank\" rel=\"noopener\">via GIPHY<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Richtig <strong>reagieren l\u00e4sst sich in mehreren Schritten<\/strong>:&nbsp;<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Antworte ruhig und sachlich, stelle falsche Behauptungen richtig und biete eine L\u00f6sungshilfe an.<\/li>\n\n\n\n<li>Merkst du, dass dein Gegen\u00fcber nicht an einer ernsthaften Diskussion interessiert ist, hei\u00dft die Devise: \u201cDon\u2019t feed the troll\u201d. Ignoriere den St\u00f6renfried. Du hast dein Bestes getan.<\/li>\n\n\n\n<li>Humorvolle Entgegnungen k\u00f6nnen helfen, Trolle blo\u00dfzustellen und zu verhindern, dass sie andere Community Mitglieder aufstacheln. Aber Vorsicht: Wenn ein User ein berechtigtes Problem hat und du dich dar\u00fcber lustig machst, geht der Schuss nach hinten los.&nbsp;<\/li>\n\n\n\n<li>Wenn Trolle offenkundig gegen die Netiquette versto\u00dfen und w\u00fcste Beleidigungen aussto\u00dfen, kann es sinnvoll sein, Kommentare zu l\u00f6schen. Allerdings solltest du das nicht \u201cwortlos\u201d machen, sondern gegen\u00fcber der Community begr\u00fcnden.&nbsp;<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Eine \u00e4hnliche Vorgehensweise empfiehlt sich bei <strong>Verschw\u00f6rungstheoretikern, wie sie in der Corona-Krise h\u00e4ufig auftauchen<\/strong>. Stelle auch hier erst einmal falsche Behauptungen richtig, idealerweise mit einer Verlinkung auf seri\u00f6se Quellen.<\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"de\" dir=\"ltr\">L\u00fcgenbusse! <a href=\"https:\/\/t.co\/kMwrVotrjd\">pic.twitter.com\/kMwrVotrjd<\/a><\/p>\u2014 Weil wir dich lieben (@BVG_Kampagne) <a href=\"https:\/\/twitter.com\/BVG_Kampagne\/status\/936204442508185601?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">November 30, 2017<\/a><\/blockquote> <script async=\"\" src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Die Berliner Verkehrsbetriebe sind ber\u00fchmt f\u00fcr ihr schlagfertiges Social Media Team.<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Community Management Tipp #7: In schwierigen Situationen deeskalieren<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Auch wenn NutzerInnen ernsthafte Kritik vorbringen, besteht die <strong>Gefahr, dass Situationen eskalieren. <\/strong>Im schlimmsten Fall entwickelt sich aus einem vermeintlich nichtigen Anlass ein ausgewachsener Shitstorm.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Damit das nicht passiert, beachte die folgenden Tipps:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Schnell reagieren: <\/strong>Je l\u00e4nger es dauert, bis dein Team auf Kritik reagiert, desto h\u00f6her ist die Gefahr, dass sich Emotionen \u201chochschaukeln\u201d und andere NutzerInnen mitgerissen werden.<\/li>\n\n\n\n<li><strong>Wertsch\u00e4tzung zeigen: <\/strong>Gib Usern von Anfang an das Gef\u00fchl, dass du ihre Kritik ernst nimmst.&nbsp;<\/li>\n\n\n\n<li><strong>Gelassen bleiben: <\/strong>Auch wenn es schwerf\u00e4llt: lass dich auf keinen Fall zu emotionalen Reaktionen hinrei\u00dfen. Das bedeutet Stress f\u00fcr dich und erh\u00f6ht die Gefahr, dass Situationen eskalieren.<\/li>\n\n\n\n<li><strong>Private Kommunikation anbieten: <\/strong>Biete NutzerInnen an, sich nicht-\u00f6ffentlich, zum Beispiel \u00fcber den Messenger auszutauschen.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Manchmal haben Community ManagerInnen das Gl\u00fcck, dass <strong>die Community schwierige Situationen f\u00fcr sie regelt, <\/strong>zum Beispiel, indem User andere wegen ungerechtfertigter Kritik zurechtweisen. Darauf solltest du dich aber nicht verlassen.<\/p>\n\n\n\t\t\n\t\t\t<div class=\"wp-block-advice\">\n\t\t\t\t<div class=\"advice__inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"advice__text text text-rich\">\n\t\t\t\t\t\t\n\n<p class=\"wp-block-paragraph\"><em>Die Social-Media-Krise ist da und was jetzt? Antworten findest du in unserem E-Book <\/em><a href=\"https:\/\/swat.io\/de\/ebooks\/krisenkommunikation-social-media\/\"><em>\u201cErfolgreiche Krisenkommunikation auf Social Media\u201d<\/em><\/a><em>, genauso wie Tipps zur Vorbeugung.<\/em><\/p>\n\n\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\n\t\t\n\n\t\t\n\t\t\t<div class=\"wp-block-cta-download \">\n\t\t\t\n\t\t\t\t<div class=\"cta-download__head headline-medium\">Erfolgreiche Krisenkommunikation auf Social Media<\/div>\t\t\t\t\t\t\t\t<div class=\"cta-download__text text text-rich\">\n\t\t\t\t\tLade dir das kostenlose eBook herunter! Du lernst verschiedene Arten von Krisen kennen und erf\u00e4hrst anhand zahlreicher Beispiele, wie du am besten mit ihnen umgehst. So bist du optimal f\u00fcr verschiedene Krisensituationen gewappnet und wei\u00dft genau, wie du souver\u00e4n reagierst, wenn es pl\u00f6tzlich Kritik hagelt oder ein Shitstorm ausbricht. Mit unserem eBook wirst du zum Profi f\u00fcr Krisenkommunikation!\t\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<footer class=\"cta-download__footer\">\n\t\t\t\t\t\t<div class=\"wp-block-buttons\">\n\t\t\t\t\t\t\t<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/swat.io\/de\/ebooks\/krisenkommunikation-social-media\/\">eBook gratis herunterladen<\/a><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/footer>\n\t\t\t\t\t\t\t<\/div>\n\t\t\n\t\t\n\n\n<h2 class=\"wp-block-heading\">Community Management Tipp #8: Verhalten bei eigenen Fehlern<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ein\/e User\/in hat guten Grund, w\u00fctend zu sein? In sozialen Medien gilt wie im echten Leben: <strong>Wer einen Fehler gemacht hat, sollte sich entschuldigen<\/strong>. F\u00fcr Community ManagerInnen bedeutet das oft, dass sie sich f\u00fcr die Fehler anderer entschuldigen. Trotzdem ist es wichtig, dies richtig zu machen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das hei\u00dft:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Gib Fehler zu (wenn es wirklich welche waren). Vermeide Ausfl\u00fcchte.<\/li>\n\n\n\n<li>Formulierungen wie \u201cEs tut mir leid, wenn du unseren Tweet als verletzend wahrgenommen hast\u201d w\u00e4lzen die Verantwortung auf den User ab. Eine verbreitete, aber nicht sehr kluge Taktik, mit der schon viele PolitikerInnen baden gegangen sind.&nbsp;<\/li>\n\n\n\n<li>Gehe pers\u00f6nlich auf die jeweilige Nutzerin ein und gib ihr die M\u00f6glichkeit, sich pers\u00f6nlich \u00fcber Kan\u00e4le wie den Messenger mit deinem Team auszutauschen.&nbsp;<\/li>\n\n\n\n<li>Wenn angebracht beziehungsweise m\u00f6glich, bem\u00fche dich um Wiedergutmachung. Manchmal reicht daf\u00fcr eine \u00f6ffentliche Stellungnahme, manchmal eine R\u00fcckerstattung von Kaufpreisen.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Denke daran: Wer sich gut entschuldigt, <strong>kann damit einen positiven Eindruck bei seiner Community hinterlassen<\/strong>. So l\u00e4sst sich aus eigenen Fehlern sogar Kapital schlagen.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Gutes Community Management ist pers\u00f6nlich<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Dass im Arbeitsalltag Routine einkehrt, l\u00e4sst sich kaum vermeiden. Doch gerade gutes Community Management lebt davon, dass du <strong>immer wieder neu und pers\u00f6nlich auf die Fragen, W\u00fcnsche und Bed\u00fcrfnisse von NutzerInnen eingehst<\/strong>, auch wenn es sich im ersten Moment nach Wiederholung anf\u00fchlt. Davon profitieren nicht nur User. Auch die eigene Arbeit f\u00fchlt sich auf diese Art lebendiger an.<\/p>\n\n\n\t\t\n\t\t\t<div class=\"wp-block-advice\">\n\t\t\t\t<div class=\"advice__inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"advice__text text text-rich\">\n\t\t\t\t\t\t\n\n<p class=\"wp-block-paragraph\"><em>Erfolgreiches Community Management h\u00e4ngt entscheidend von einem guten Social Media Management Tool ab. Mit Swat.io profitierst du von vielen wertvollen Funktionen f\u00fcr die Kommunikation mit deinen Followern, angefangen bei einer zentralen Ticket Inbox f\u00fcr Kommentare, Postings, Erw\u00e4hnungen und Privatnachrichten. Starte jetzt eine kostenlose Trial und erlebe den Unterschied.<\/em><\/p>\n\n\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\n\t\t\n\n\t\t\n\t\t\t<div class=\"wp-block-cta-form wp-block-cta-form--demo\">\n\t\t\t\t<div class=\"cta-form__container\">\n\t\t\t\t\t\t\t\t\t\t<header class=\"cta-form__header\">\n\t\t\t\t\t\t<div class=\"cta-form__title headline-medium\">Effiziente Social Media Kommunikation mit Swat.io<\/div>\t\t\t\t\t\t\n\t\t\t\t\t<\/header>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<footer class=\"cta-form__footer\">\n\t\t\t\t\t\t<a class=\"cta-form__button button button--primary\" href=\"https:\/\/swat.io\/de\/preise\">Jetzt kostenlos testen<\/a>\t\t\t\t\t\t\t\n\t\t\t\t\t<\/footer>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\n\t\t","protected":false},"excerpt":{"rendered":"<p>Wir haben uns an dieser Stelle schon mit strategischen Fragen zum Community Management, effizienten Workflows oder Krisenkommunikation besch\u00e4ftigt. Aber was\u2026<\/p>\n","protected":false},"author":59,"featured_media":20618,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[532],"tags":[104],"class_list":["entry","entry--post"],"_links":{"self":[{"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/posts\/20620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/comments?post=20620"}],"version-history":[{"count":11,"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/posts\/20620\/revisions"}],"predecessor-version":[{"id":57067,"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/posts\/20620\/revisions\/57067"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/media\/20618"}],"wp:attachment":[{"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/media?parent=20620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/categories?post=20620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/tags?post=20620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}