{"id":46633,"date":"2024-06-13T08:32:45","date_gmt":"2024-06-13T06:32:45","guid":{"rendered":"https:\/\/swat.io\/?p=46633"},"modified":"2024-06-13T08:32:47","modified_gmt":"2024-06-13T06:32:47","slug":"linkedin-document-posts","status":"publish","type":"post","link":"https:\/\/swat.io\/de\/publizieren\/linkedin-document-posts\/","title":{"rendered":"Alles, was du 2024 \u00fcber LinkedIn Document Posts wissen musst"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Vor Kurzem hat LinkedIn die <a href=\"https:\/\/www.linkedin.com\/help\/linkedin\/answer\/a764804\" target=\"_blank\" rel=\"noopener\">Carousel Posts eingestellt<\/a>. Doch mit <strong>LinkedIn Document Posts <\/strong>gibt es eine beliebte Alternative, die \u00e4hnlich funktioniert, vielseitig verwendbar ist und ein gro\u00dfes Potenzial f\u00fcr deine Reichweite mitbringt.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hier erf\u00e4hrst du,<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>warum LinkedIn Document Posts so effektiv sind,&nbsp;<\/li>\n\n\n\n<li>wie du sie erstellst und<\/li>\n\n\n\n<li>worauf du bei der Erstellung achten solltest.&nbsp;&nbsp;<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Was sind LinkedIn Document Posts?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Bei LinkedIn Document Posts handelt es sich um <strong>Dokumente, die als Slideshow dargestellt werden<\/strong>. Nutzer:innen sehen zun\u00e4chst nur die erste Seite im Feed und k\u00f6nnen dann durch den Rest des Dokumentes scrollen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gut zu wissen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ein LinkedIn Document Post kann aus bis zu 300 Seiten bestehen und maximal 100 MB gro\u00df sein.<\/li>\n\n\n\n<li>LinkedIn unterst\u00fctzt die folgenden Dateiformate: PPT, PPTX, DOC, DOCX und PDF.<\/li>\n\n\n\n<li>Alle Mitglieder, die deinen Post sehen, d\u00fcrfen das Dokument herunterladen.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Klingt unspektakul\u00e4r? Mag sein, funktioniert aber.<\/p>\n\n\n\t\t\n\t\t\t<div class=\"wp-block-advice\">\n\t\t\t\t<div class=\"advice__inner\">\n\t\t\t\t\t<div class=\"advice__head headline-small\">Achtung!<\/div>\t\t\t\t\t<div class=\"advice__text text text-rich\">\n\t\t\t\t\t\t\n\n<p class=\"wp-block-paragraph\"><em>Falls du keine eingebetteten LinkedIn-Posts in diesem Beitrag siehst, liegt es daran, dass du Marketing-Cookies nicht akzeptiert hast. Bitte leere deinen Browser-Cache und akzeptiere alle Cookies, um den Beitrag korrekt angezeigt zu bekommen.<\/em><\/p>\n\n\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\n\t\t\n\n\n<h2 class=\"wp-block-heading\">Warum du LinkedIn Dokument Posts nutzen solltest<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Einige Eigenschaften machen LinkedIn Document Posts zu attraktiven Formaten im B2B-Marketing auf der sozialen Plattform.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Interaktiv: <\/strong>User:innen sehen zun\u00e4chst nur eine Seite beziehungsweise Folie. Im g\u00fcnstigsten Fall beginnen sie dann, zu scrollen, bis sie den kompletten Inhalt gelesen haben. Damit erzeugen Document Posts Engagement und sorgen daf\u00fcr, dass sich User:innen lange mit deinen Inhalten auseinandersetzen (Verweildauer). Beides belohnt LinkedIn mit mehr Reichweite.<\/li>\n\n\n\n<li><strong>Vielseitig einsetzbar<\/strong>: Ob Tutorial, Branchennews oder Produkteinf\u00fchrung, LinkedIn Slider Posts eignen sich f\u00fcr unterschiedliche Formate und Einsatzzwecke. Darauf kommen wir noch zur\u00fcck.<\/li>\n\n\n\n<li><strong>Einfach konsumierbar: <\/strong>Im hektischen digitalen Alltag konsumieren viele Menschen Content am liebsten in H\u00e4ppchen. Slide-Pr\u00e4sentationen mit Bildern, Bulletpoints und Fokus auf Kernaussagen sind leichter verdaulich als lange Fachartikel.&nbsp;<\/li>\n\n\n\n<li><strong>Ideal f\u00fcr Storytelling:<\/strong> Mit Document Posts kannst du Geschichten erz\u00e4hlen, die deine Zielgruppe emotional ber\u00fchren und Verbindungen zu deiner Marke kn\u00fcpfen. Zwar kannst du aktuell keine Videos einbinden, aber Bilder und andere grafische Gestaltungsmerkmale.&nbsp;&nbsp;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Dazu kommt ein weiterer Vorteil: LinkedIn Document Posts sind einfach zu erstellen und hochzuladen. Du musst auch nicht unbedingt neuen Content erstellen. Das Format ist ideal, um vorhandene Inhalte zu recyceln.<\/p>\n\n\n\t\t\n\t\t\t<div class=\"wp-block-advice\">\n\t\t\t\t<div class=\"advice__inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"advice__text text text-rich\">\n\t\t\t\t\t\t\n\n<p class=\"wp-block-paragraph\"><em>Du suchst nach Wegen, deine Reichweite auf LinkedIn zu vergr\u00f6\u00dfern? Lies jetzt unseren Artikel <\/em><a href=\"https:\/\/swat.io\/de\/lernen\/linkedin-reichweite-erhoehen\/\"><em>\u201cWie du die LinkedIn-Reichweite deines Unternehmens erh\u00f6hst und mehr Sichtbarkeit erzielst\u201d<\/em><\/a><em>.<\/em><\/p>\n\n\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\n\t\t\n\n\n<h2 class=\"wp-block-heading\">LinkedIn Document Posts erstellen: Schritt-f\u00fcr-Schritt-Anleitung<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ein LinkedIn Document Post ist zun\u00e4chst nichts anderes als ein Dokument.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Allerdings raten wir dir davon ab, einfach irgendein Whitepaper als PDF-Datei hochzuladen und es dabei zu belassen. Denn wahrscheinlich sieht das Resultat als Slideshow wenig attraktiv aus. Au\u00dferdem sehen sich User:innen Dokumente oft auf dem Handy an beziehungsweise vergr\u00f6\u00dfern sie nicht.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Erstelle Document Posts deshalb lieber gezielt mit einem Tool wie <strong>Canva<\/strong> oder <strong>Adobe Express<\/strong> und speichere sie dann als PDF ab. Achte wie im folgenden Beispiel auf eine gute Lesbarkeit und \u00fcbersichtliche Gestaltung.&nbsp;<\/p>\n\n\n\n<center> <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"linkedin\" data-borlabs-cookie-content=\"PGlmcmFtZSBzcmM9Imh0dHBzOi8vd3d3LmxpbmtlZGluLmNvbS9lbWJlZC9mZWVkL3VwZGF0ZS91cm46bGk6dWdjUG9zdDo3MTc2MTI1OTI1NTUyNDkyNTQ0IiBoZWlnaHQ9IjEzMDAiIHdpZHRoPSI1MDQiIGZyYW1lYm9yZGVyPSIwIiBhbGxvd2Z1bGxzY3JlZW49IiIgdGl0bGU9IkVpbmdlYmV0dGV0ZXIgQmVpdHJhZyI+PC9pZnJhbWU+\"><div class=\"brlbs-cmpnt-cb-preset-a\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>LinkedIn<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf den Button unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Weitere Informationen<\/a> <\/div><\/div><\/center>\n\n\n\n<p class=\"wp-block-paragraph\">Um sie auf <strong>LinkedIn hochzuladen<\/strong>, gehe folgenderma\u00dfen vor:&nbsp;<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Gehe auf \u201cBeitrag beginnen\u201d und auf \u201cMehr\u201d.<\/li>\n\n\n\n<li>W\u00e4hle \u201cDokument hinzuf\u00fcgen\u201d.&nbsp;<\/li>\n\n\n\n<li>Lade die Datei hoch.<\/li>\n\n\n\n<li>F\u00fcge einen Titel hinzu.<\/li>\n\n\n\n<li>Formuliere eine kurze (!) Einleitung, die neugierig macht.&nbsp;<\/li>\n\n\n\n<li>Schlie\u00dfe den Vorgang mit \u201cPosten\u201d ab.&nbsp;<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\">Daf\u00fcr eignen sich LinkedIn Slider<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">LinkedIn Slider sind ein Allzweckmittel im Content Marketing. Besonders gut <strong>eignen sie sich f\u00fcr folgende Anwendungszwecke.&nbsp;<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Case Studies<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">In Case Studies kannst du beleuchten, welche Leistungen dein Unternehmen f\u00fcr ein anderes Unternehmen erbracht hat und welcher Mehrwert daraus erwachsen ist. Nutze das Slider-Format, um <strong>auf einzelnen Seiten Ausgangslage, Problem, L\u00f6sung und Nutzen zu schildern<\/strong>. Wecke Neugier darauf, wie es dir gelungen ist, die jeweilige Herausforderung zu l\u00f6sen, und binde Testimonials ein.&nbsp;<\/p>\n\n\n\n<center> <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"linkedin\" data-borlabs-cookie-content=\"PGlmcmFtZSBzcmM9Imh0dHBzOi8vd3d3LmxpbmtlZGluLmNvbS9lbWJlZC9mZWVkL3VwZGF0ZS91cm46bGk6dWdjUG9zdDo3MTk1NjQ5NTY3NTEyNTc2MDAwIiBoZWlnaHQ9IjExMzEiIHdpZHRoPSI1MDQiIGZyYW1lYm9yZGVyPSIwIiBhbGxvd2Z1bGxzY3JlZW49IiIgdGl0bGU9IkVpbmdlYmV0dGV0ZXIgQmVpdHJhZyI+PC9pZnJhbWU+\"><div class=\"brlbs-cmpnt-cb-preset-a\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>LinkedIn<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf den Button unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Weitere Informationen<\/a> <\/div><\/div><\/center>\n\n\n\n<h3 class=\"wp-block-heading\">Tutorials<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Positioniere deine Marke als Experte, indem du <strong>leicht verst\u00e4ndliche Anleitungen f\u00fcr ein Problem postest,<\/strong> das f\u00fcr deine Zielgruppe relevant ist. Pr\u00e4sentiere einen Schritt pro Seite mit entsprechendem Bild. So k\u00f6nnen sich User:innen bis zur L\u00f6sung durchscrollen.&nbsp;<\/p>\n\n\n\n<center> <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"linkedin\" data-borlabs-cookie-content=\"PGlmcmFtZSBzcmM9Imh0dHBzOi8vd3d3LmxpbmtlZGluLmNvbS9lbWJlZC9mZWVkL3VwZGF0ZS91cm46bGk6dWdjUG9zdDo3MTk1NjQwMjQ4MTQ2NTc5NDU2IiBoZWlnaHQ9IjY2OSIgd2lkdGg9IjUwNCIgZnJhbWVib3JkZXI9IjAiIGFsbG93ZnVsbHNjcmVlbj0iIiB0aXRsZT0iRWluZ2ViZXR0ZXRlciBCZWl0cmFnIj48L2lmcmFtZT4=\"><div class=\"brlbs-cmpnt-cb-preset-a\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>LinkedIn<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf den Button unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Weitere Informationen<\/a> <\/div><\/div><\/center>\n\n\n\n<h3 class=\"wp-block-heading\">Branchen-Insights<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Kommuniziere wichtige Neuigkeiten aus deiner Branche. <strong>Umfrageergebnisse oder Statistiken<\/strong> lassen sich beispielsweise sehr gut auf verschiedene Slides aufteilen.&nbsp;<\/p>\n\n\n\n<center> <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"linkedin\" data-borlabs-cookie-content=\"PGlmcmFtZSBzcmM9Imh0dHBzOi8vd3d3LmxpbmtlZGluLmNvbS9lbWJlZC9mZWVkL3VwZGF0ZS91cm46bGk6dWdjUG9zdDo3MTkxNjYzMzc2MDY0Nzc4MjQwIiBoZWlnaHQ9IjE4NDgiIHdpZHRoPSI1MDQiIGZyYW1lYm9yZGVyPSIwIiBhbGxvd2Z1bGxzY3JlZW49IiIgdGl0bGU9IkVpbmdlYmV0dGV0ZXIgQmVpdHJhZyI+PC9pZnJhbWU+\"><div class=\"brlbs-cmpnt-cb-preset-a\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>LinkedIn<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf den Button unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Weitere Informationen<\/a> <\/div><\/div><\/center>\n\n\n\n<p class=\"wp-block-paragraph\">Das hei\u00dft nicht, dass du alle Ergebnisse in einem Document Post pr\u00e4sentieren musst. Du kannst diesen auch als <strong>Teaser verwenden wie in folgendem Fall.<\/strong><\/p>\n\n\n\n<center> <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"linkedin\" data-borlabs-cookie-content=\"PGlmcmFtZSBzcmM9Imh0dHBzOi8vd3d3LmxpbmtlZGluLmNvbS9lbWJlZC9mZWVkL3VwZGF0ZS91cm46bGk6dWdjUG9zdDo3MTM4NDg5OTAwMTQ3ODcxNzQ3IiBoZWlnaHQ9IjEzMjAiIHdpZHRoPSI1MDQiIGZyYW1lYm9yZGVyPSIwIiBhbGxvd2Z1bGxzY3JlZW49IiIgdGl0bGU9IkVpbmdlYmV0dGV0ZXIgQmVpdHJhZyI+PC9pZnJhbWU+\"><div class=\"brlbs-cmpnt-cb-preset-a\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>LinkedIn<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf den Button unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Weitere Informationen<\/a> <\/div><\/div><\/center>\n\n\n\n<p class=\"wp-block-paragraph\">Der Vorteil davon: Die Chance steigt, dass User:innen ihre Kontaktdaten hinterlegen, um den Rest zu sehen.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Umgekehrt gibt es F\u00e4lle, in denen es tats\u00e4chlich Sinn ergibt, ganze <strong>Brosch\u00fcren und\/oder Whitepaper als Dokument hochzuladen<\/strong>. Manche Themen lassen sich nicht in ein paar Bulletpoints abhandeln.&nbsp;<\/p>\n\n\n\n<center> <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"linkedin\" data-borlabs-cookie-content=\"PGlmcmFtZSBzcmM9Imh0dHBzOi8vd3d3LmxpbmtlZGluLmNvbS9lbWJlZC9mZWVkL3VwZGF0ZS91cm46bGk6dWdjUG9zdDo3MTcxNDA3MDczNTcyODM5NDI0IiBoZWlnaHQ9IjEyNTciIHdpZHRoPSI1MDQiIGZyYW1lYm9yZGVyPSIwIiBhbGxvd2Z1bGxzY3JlZW49IiIgdGl0bGU9IkVpbmdlYmV0dGV0ZXIgQmVpdHJhZyI+PC9pZnJhbWU+\"><div class=\"brlbs-cmpnt-cb-preset-a\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>LinkedIn<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf den Button unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Weitere Informationen<\/a> <\/div><\/div><\/center>\n\n\n\t\t\n\t\t\t<div class=\"wp-block-advice\">\n\t\t\t\t<div class=\"advice__inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"advice__text text text-rich\">\n\t\t\t\t\t\t\n\n<p class=\"wp-block-paragraph\"><em>Tipp: Entscheidend daf\u00fcr, wie tiefgehend Document Posts sein sollten, ist die Bereitschaft deiner Zielgruppe.<\/em><\/p>\n\n\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\n\t\t\n\n\n<h3 class=\"wp-block-heading\">Behind the Scenes<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Tauche <strong>hinter die Kulissen deiner Marke oder deines Unternehmens<\/strong> ab. Stelle einzelne Mitglieder deines Teams vor oder mache mit User:innen einen virtuellen Rundgang durch Unternehmensgeb\u00e4ude.<\/p>\n\n\n\n<center> <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"linkedin\" data-borlabs-cookie-content=\"PGlmcmFtZSBzcmM9Imh0dHBzOi8vd3d3LmxpbmtlZGluLmNvbS9lbWJlZC9mZWVkL3VwZGF0ZS91cm46bGk6dWdjUG9zdDo3MTczNTk2NjEwNTU0MTI2MzM2IiBoZWlnaHQ9IjgzNyIgd2lkdGg9IjUwNCIgZnJhbWVib3JkZXI9IjAiIGFsbG93ZnVsbHNjcmVlbj0iIiB0aXRsZT0iRWluZ2ViZXR0ZXRlciBCZWl0cmFnIj48L2lmcmFtZT4=\"><div class=\"brlbs-cmpnt-cb-preset-a\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>LinkedIn<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf den Button unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Weitere Informationen<\/a> <\/div><\/div><\/center>\n\n\n\n<h3 class=\"wp-block-heading\">Event-Highlights<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Du warst auf einer Veranstaltung, die f\u00fcr deine Zielgruppe relevant ist? Stelle deine <strong>Eindr\u00fccke in einem LinkedIn Document Post<\/strong> zusammen.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Produktvorstellung&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Pr\u00e4sentiere Produktupdates oder -neuheiten, indem du ihre <strong>zentralen Features und Vorteile auf mehreren Seiten hervorhebst:<\/strong><\/p>\n\n\n\n<center> <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"linkedin\" data-borlabs-cookie-content=\"PGlmcmFtZSBzcmM9Imh0dHBzOi8vd3d3LmxpbmtlZGluLmNvbS9lbWJlZC9mZWVkL3VwZGF0ZS91cm46bGk6dWdjUG9zdDo3MTkyMTcxMzI5MTg4NDUwMzA2IiBoZWlnaHQ9IjY4NyIgd2lkdGg9IjUwNCIgZnJhbWVib3JkZXI9IjAiIGFsbG93ZnVsbHNjcmVlbj0iIiB0aXRsZT0iRWluZ2ViZXR0ZXRlciBCZWl0cmFnIj48L2lmcmFtZT4=\"><div class=\"brlbs-cmpnt-cb-preset-a\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>LinkedIn<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf den Button unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Weitere Informationen<\/a> <\/div><\/div><\/center>\n\n\n\n<center> <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"linkedin\" data-borlabs-cookie-content=\"PGlmcmFtZSBzcmM9Imh0dHBzOi8vd3d3LmxpbmtlZGluLmNvbS9lbWJlZC9mZWVkL3VwZGF0ZS91cm46bGk6dWdjUG9zdDo3MTc2NDg4MTczNzY4NzI4NTc5IiBoZWlnaHQ9IjcwOCIgd2lkdGg9IjUwNCIgZnJhbWVib3JkZXI9IjAiIGFsbG93ZnVsbHNjcmVlbj0iIiB0aXRsZT0iRWluZ2ViZXR0ZXRlciBCZWl0cmFnIj48L2lmcmFtZT4=\"><div class=\"brlbs-cmpnt-cb-preset-a\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>LinkedIn<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf den Button unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Weitere Informationen<\/a> <\/div><\/div>\n<\/center>\n\n\n\n<h2 class=\"wp-block-heading\">Best Practices f\u00fcr LinkedIn Document Posts<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Lege Wert auf einen guten Einstieg<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Die <strong>erste Seite deines Dokuments entscheidet<\/strong> dar\u00fcber, ob User:innen neugierig auf den Rest sind.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Achte deshalb darauf, sie ansprechend zu gestalten. Formuliere einen aussagekr\u00e4ftigen Titel. Mache deutlich, welchen Mehrwert sich Leser:innen von der Lekt\u00fcre versprechen k\u00f6nnen.&nbsp;<\/p>\n\n\n\n<center> <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"linkedin\" data-borlabs-cookie-content=\"PGlmcmFtZSBzcmM9Imh0dHBzOi8vd3d3LmxpbmtlZGluLmNvbS9lbWJlZC9mZWVkL3VwZGF0ZS91cm46bGk6dWdjUG9zdDo3MTg1NzU4MjI5NjYwOTM0MTQ0P2NvbXBhY3Q9MSIgaGVpZ2h0PSIzOTkiIHdpZHRoPSI3MTAiIGZyYW1lYm9yZGVyPSIwIiBhbGxvd2Z1bGxzY3JlZW49IiIgdGl0bGU9IkVpbmdlYmV0dGV0ZXIgQmVpdHJhZyI+PC9pZnJhbWU+\"><div class=\"brlbs-cmpnt-cb-preset-a\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>LinkedIn<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf den Button unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Weitere Informationen<\/a> <\/div><\/div><\/center>\n\n\n\t\t\n\t\t\t<div class=\"wp-block-advice\">\n\t\t\t\t<div class=\"advice__inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"advice__text text text-rich\">\n\t\t\t\t\t\t\n\n<p class=\"wp-block-paragraph\"><strong><em>Wichtig: <\/em><\/strong><em>Auch wenn es dir unter den N\u00e4geln brennt, so viele Menschen wie m\u00f6glich auf deinen Document Post aufmerksam zu machen, trage nicht zu dick auf. \u00dcberfrachte speziell deine Titelseite nicht mit bunten Farben und Effekten. Sonst wirkt das Ergebnis unprofessionell, und das ist (nicht nur) auf LinkedIn ein No-Go.<\/em><\/p>\n\n\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\n\t\t\n\n\n<h3 class=\"wp-block-heading\">Auf die Optik kommt es an<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Professionell ist wichtig, aber die wenigsten Menschen wollen Document Posts, die wie Doktorarbeiten aussehen. Ansprechend wirken Slideshows durch den <strong>gezielten Einsatz von Farben, ein passendes, harmonisches Design und Bilder, die Emotionen wecken.<\/strong> Du musst kein Designer sein, um diese Voraussetzungen zu erf\u00fcllen. Aber es kann helfen, sich von Profis unterst\u00fctzen zu lassen.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Halte dich kurz<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Dieser Ratschlag gilt f\u00fcr die L\u00e4nge deiner Slide Show und f\u00fcr den Text. Beschr\u00e4nke dich lieber auf <strong>weniger Seiten und bevorzuge eine klare, gut verst\u00e4ndliche Sprache.<\/strong> Fokussiere dich auf zentrale Aussagen und verzichte auf Drumherum.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Erz\u00e4hle Geschichten<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Wo m\u00f6glich, verwende<strong> Storytelling-Strategien<\/strong>. Das kann ein einfacher dreistufiger Aufbau sein wie im Konzept \u201cProblem \u2013 Dramatisierung (des Problems) \u2013 L\u00f6sung\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Setze Figuren und Situationen ein, mit denen sich deine Zielgruppe identifizieren kann.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Denke an den Call to Action<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Wahrscheinlich bist du noch nicht hundertprozentig damit zufrieden, wenn User:innen deinen Document Post lesen. Du w\u00fcnschst dir au\u00dferdem, dass sie zum Beispiel deine Website besuchen oder Kontakt mit dir beziehungsweise deinem Unternehmen aufnehmen.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dann vergiss nicht, es Ihnen zu sagen. Ein <strong>klarer Call to Action<\/strong> geh\u00f6rt ans Ende jedes Document Posts.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Verwende Document Posts zur Leadgewinnung&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Wir haben es schon angerissen: Mit Slider Posts kannst du <strong>wertvolle neue Kontakte kn\u00fcpfen. <\/strong>Verwende dein Dokument als Teaser und mache den Rest f\u00fcr User:innen zug\u00e4nglich, die ihre Kontaktdaten hinterlegen. Oder verweise am Ende auf deinen Newsletter.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"429\" height=\"531\" src=\"https:\/\/swat.io\/wp-content\/uploads\/2024\/06\/linkedin-document-post-document-posts.png\" alt=\"\" class=\"wp-image-46631\" srcset=\"https:\/\/swat.io\/wp-content\/uploads\/2024\/06\/linkedin-document-post-document-posts.png 429w, https:\/\/swat.io\/wp-content\/uploads\/2024\/06\/linkedin-document-post-document-posts-300x371.png 300w\" sizes=\"(max-width: 429px) 100vw, 429px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Einfaches, aber effektives Prinzip<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Der Name Document Post klingt nicht gerade aufregend. Das Gleiche gilt f\u00fcr die Idee, mehrseitige PDFs oder PowerPoint-Dateien auf LinkedIn hochzuladen.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Doch in der Praxis erweist sich das Prinzip der Slideshows als \u00e4u\u00dferst effektiv, um <strong>mehr Sichtbarkeit zu erzielen, die eigene Reichweite zu vergr\u00f6\u00dfern und wertvolle Leads zu gewinnen. <\/strong>Allerdings profitierst du von diesen Vorteilen am meisten, wenn du nicht einfach irgendwelche Dokumente auf LinkedIn hochl\u00e4dst, sondern deine Slides ansprechend und kompakt gestaltest.&nbsp;<\/p>\n\n\n\t\t\n\t\t\t<div class=\"wp-block-advice\">\n\t\t\t\t<div class=\"advice__inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"advice__text text text-rich\">\n\t\t\t\t\t\t\n\n<p class=\"wp-block-paragraph\"><em>Egal ob Document Post oder anderes Format, LinkedIn, TikTok oder Instagram, mit Swat.io ist Planen und Posten auf Social Media ein Kinderspiel. Dasselbe gilt f\u00fcr die Interaktion mit deiner Community, das Durchf\u00fchren von Analysen und alle anderen Ma\u00dfnahmen, die f\u00fcr erfolgreiches Social Media Marketing notwendig sind. Probier es jetzt kostenlos aus!<\/em><\/p>\n\n\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\n\t\t\n\n\t\t\n\t\t\t<div class=\"wp-block-cta-form wp-block-cta-form--demo\">\n\t\t\t\t<div class=\"cta-form__container\">\n\t\t\t\t\t\t\t\t\t\t<header class=\"cta-form__header\">\n\t\t\t\t\t\t<div class=\"cta-form__title headline-medium\">Effiziente Social Media Kommunikation mit Swat.io<\/div>\t\t\t\t\t\t\n\t\t\t\t\t<\/header>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<footer class=\"cta-form__footer\">\n\t\t\t\t\t\t<a class=\"cta-form__button button button--primary\" href=\"https:\/\/swat.io\/de\/preise\">Jetzt kostenlos testen<\/a>\t\t\t\t\t\t\t\n\t\t\t\t\t<\/footer>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\n\t\t","protected":false},"excerpt":{"rendered":"<p>Vor Kurzem hat LinkedIn die Carousel Posts eingestellt. Doch mit LinkedIn Document Posts gibt es eine beliebte Alternative, die \u00e4hnlich\u2026<\/p>\n","protected":false},"author":59,"featured_media":46636,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[536],"tags":[539,853],"class_list":["entry","entry--post"],"_links":{"self":[{"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/posts\/46633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/comments?post=46633"}],"version-history":[{"count":7,"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/posts\/46633\/revisions"}],"predecessor-version":[{"id":46659,"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/posts\/46633\/revisions\/46659"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/media\/46636"}],"wp:attachment":[{"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/media?parent=46633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/categories?post=46633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/tags?post=46633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}