{"id":15389,"date":"2019-12-19T14:55:47","date_gmt":"2019-12-19T14:55:47","guid":{"rendered":"https:\/\/swat.io\/?post_type=swatio_wiki&#038;p=15389"},"modified":"2022-08-10T08:34:01","modified_gmt":"2022-08-10T06:34:01","slug":"social-media","status":"publish","type":"swatio_wiki","link":"https:\/\/swat.io\/de\/wiki\/social-media\/","title":{"rendered":"Social Media"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Social Media bzw. Soziale Medien dienen vorrangig der <strong>Vernetzung und dem Austausch von Inhalten im Internet<\/strong>. In der modernen Gesellschaft spielen sie eine wichtige Rolle f\u00fcr die Kommunikation zwischen Privatpersonen, Unternehmen und Organisationen. <a href=\"https:\/\/swat.io\/de\/wiki\/social-media-marketing\/\">Social Media Marketing<\/a> hat sich au\u00dferdem zu einem zentralen Bestandteil von <a href=\"https:\/\/swat.io\/de\/wiki\/social-media-werbung\/\">Werbung<\/a> entwickelt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zu den wichtigsten und gr\u00f6\u00dften sozialen Medien geh\u00f6ren <strong><a href=\"https:\/\/swat.io\/de\/wiki\/facebook\/\">Facebook<\/a>, <a href=\"https:\/\/swat.io\/de\/wiki\/instagram\/\">Instagram<\/a> und <a href=\"https:\/\/swat.io\/de\/wiki\/twitter\/\">Twitter<\/a><\/strong>. Daneben existiert eine Reihe von Nischenplattformen. W\u00e4hrend sich beide Formen als Bestandteil der digitalen Gegenwart etabliert haben, sind sie auch immer wieder Gegenstand von Kritik. So wird Social Media regelm\u00e4\u00dfig vorgeworfen, dass sie als Plattformen dienen, um extremistische \u00c4u\u00dferungen und <a href=\"https:\/\/swat.io\/de\/wiki\/fake-news\/\" class=\"rank-math-link\">Falschmeldungen<\/a> zu verbreiten, Meinungen zu manipulieren und politische Ereignisse negativ zu beeinflussen. Au\u00dferdem machten <a href=\"https:\/\/swat.io\/de\/wiki\/social-media-kanaele\/\">Social Media Kan\u00e4le<\/a> wie Facebook in der Vergangenheit mit mehreren Datenskandalen von sich reden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Definition<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Der Begriff soziale Medien oder auch Social Media beschreibt Medien, mit deren Hilfe Nutzer \u00fcber digitale Kan\u00e4le kommunizieren und interagieren. Im Mittelpunkt dabei stehen die Interaktivit\u00e4t und der Austausch von User-Generated Content.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Meistens ist in Zusammenhang mit Social Media bzw. sozialen Medien die Rede von sozialen Netzwerken wie Facebook oder auch Instagram. Allerdings fallen unter den Begriff auch unternehmensinterne soziale Netzwerke, Foren, Blogs, virtuelle Welten oder soziale Spiele.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Funktionen und Charakteristika sozialer Medien<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wie bereits erw\u00e4hnt, dienen Social Media vorrangig dem <strong>Austausch und der Kommunikation<\/strong>. Nutzer erstellen Inhalte und teilen diese mit ihren Followern oder Freunden. Die Inhalte k\u00f6nnen je nach Netzwerk auf Text, Fotos, Videos oder anderen Elementen, wie zum Beispiel Animationen, basieren. Au\u00dferdem besteht die M\u00f6glichkeit, Inhalte anderer Nutzer zu kommentieren, auf sie zu reagieren (zum Beispiel mit einem Like) und sie weiter zu teilen. In den meisten Medien m\u00fcssen Nutzer zuerst ein <strong>Benutzerprofil<\/strong> einrichten, um an diesem Austausch teilzunehmen. Unternehmen stehen oft spezifische <strong>Unternehmensprofile<\/strong> zur Verf\u00fcgung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Daneben besteht zum Beispiel die Option, verschiedene Inhalte zu \u201e<a href=\"https:\/\/swat.io\/de\/wiki\/stories\/\">Stories<\/a>\u201c zusammenzusetzen und zu ver\u00f6ffentlichen. In Gruppen k\u00f6nnen sich Nutzer, die ein bestimmtes Interesse teilen, zusammenschlie\u00dfen. Viele Funktionen gro\u00dfer Netzwerke \u00fcberschneiden sich. Daneben gibt es gravierende Unterschiede. So konzentriert sich Instagram ganz auf visuelle Inhalte, Twitter dagegen auf Kurznachrichten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Vorteile, Nachteile und Kritik<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Social Media bringen viele Vorteile mit sich, die ihre rasante Verbreitung begr\u00fcnden. Dazu geh\u00f6rt, dass sie die unkomplizierte Kommunikation und den schnellen Austausch von Informationen unabh\u00e4ngig von Ort und Zeit erm\u00f6glichen. Privatpersonen k\u00f6nnen auf diesem Weg leichter miteinander in Kontakt bleiben und Fotos oder Videos aus ihrem Leben mit Freunden teilen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im Onlinemarketing punkten Social Media mit folgenden Vorteilen:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Durch die <strong>gro\u00dfe Reichweite<\/strong> von Netzwerken wie Facebook oder Instagram k\u00f6nnen Unternehmen mit vergleichsweise geringem Aufwand eine gro\u00dfe Zahl an Menschen erreichen.<\/li><li>Im <strong>Content Marketing<\/strong> ist der Unterschied zwischen \u201enormalen\u201c Inhalten und Werbung oft kaum ersichtlich. Dies erh\u00f6ht die Bereitschaft von Adressaten, sich freiwillig mit Werbung zu besch\u00e4ftigen. Zus\u00e4tzlich k\u00f6nnen Unternehmen Inhalte von anderen Nutzern, zum Beispiel <a href=\"https:\/\/swat.io\/de\/wiki\/influencer\/\">Influencern<\/a>, in ihre Marketingstrategie einbinden.<\/li><li>Social Media sind ideal f\u00fcr die <strong>direkte Kommunikation<\/strong> mit Kunden.<\/li><li>Durch die <strong>F\u00fclle an Daten<\/strong>, die soziale Netzwerke \u00fcber ihre Benutzer sammeln, und zahlreiche M\u00f6glichkeiten des Targetings lassen sich sehr gezielt einzelne Zielgruppen adressieren.<\/li><li>Soziale Medien eignen sich auch f\u00fcr andere Einsatzzwecke, zum Beispiel f\u00fcr das <strong>Recruiting<\/strong>.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Allerdings gibt es in Bezug auf Social Media auch verschiedene Nachteile und Risiken zu beachten. Das gilt in besonderer Weise f\u00fcr den Datenschutz. Mehrere Datenskandale in der Vergangenheit haben gezeigt, dass Social Media nicht immer rechtskonform mit Nutzerdaten umgehen. [1] Ebenfalls bekannt ist, dass radikale Gruppen und Parteien soziale Medien nutzen, um Falschmeldungen zu verbreiten und politische Debatten zu lenken.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unternehmen, die <a href=\"https:\/\/swat.io\/de\/funktionen\/social-media-management\/\" class=\"rank-math-link\">Social Media Marketing<\/a> betreiben, sind au\u00dferdem mit der Gefahr konfrontiert, dass sich negative Meinungen \u00fcber sie in sozialen Medien schnell verbreiten und zu einem betr\u00e4chtlichen Imageschaden f\u00fchren k\u00f6nnen. Au\u00dferdem ist die Konkurrenz gerade in Medien wie Facebook mittlerweile so gro\u00df, dass vielfach <a href=\"https:\/\/swat.io\/de\/wiki\/social-media-werbung\/\">bezahlte Werbung<\/a> notwendig ist, um die gew\u00fcnschte Reichweite zu erzielen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Die wichtigsten Social Media Netzwerke<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Zu den bedeutendsten sozialen Netzwerken geh\u00f6ren aktuell die folgenden:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Facebook<\/strong>: Mit 2,27 Milliarden monatlich aktiven Nutzer (Stand: Januar 2019) ist <a href=\"https:\/\/swat.io\/de\/wiki\/facebook\/\">Facebook<\/a> das gr\u00f6\u00dfte soziale Netzwerk der Welt. Es wird auch im Onlinemarketing besonders h\u00e4ufig genutzt. Allerdings stellt Facebook auch das soziale Medium dar, das in der Vergangenheit mit besonders vielen Datenskandalen Kritik auf sich gezogen hat.<\/li><li><strong>YouTube<\/strong>: Ebenfalls zu den beliebtesten sozialen Netzwerken geh\u00f6rt das Videoportal <a href=\"https:\/\/swat.io\/de\/wiki\/youtube\/\">YouTube<\/a>.<\/li><li><strong>Instagram<\/strong>: <a href=\"https:\/\/swat.io\/de\/wiki\/instagram\/\">Instagram<\/a> konzentriert sich auf die mobile Nutzung und virtuelle Inhalte, sowohl Fotos als auch Videos. Instagram und YouTube nehmen eine Spitzenstellung im Influencer Marketing ein, bei dem sich Unternehmen Meinungsf\u00fchrern in sozialen Medien bedienen.<\/li><li><strong>Snapchat<\/strong>: <a href=\"https:\/\/swat.io\/de\/wiki\/snapchat\/\">Snapchat<\/a> ist besonders bei jungen Menschen verbreitet und basiert auf dem Verschicken von virtuellen Inhalten, die nach kurzer Zeit wieder verschwinden.<\/li><li><strong>Twitter<\/strong>: Bei <a href=\"https:\/\/swat.io\/de\/wiki\/twitter\/\">Twitter<\/a> handelt es sich um einen Kurznachrichtendienst, der besonders im B2B Marketing eine wichtige Rolle spielt.<\/li><li><strong>WhatsApp<\/strong>: <a href=\"https:\/\/swat.io\/de\/wiki\/whatsapp\/\">WhatsApp<\/a> stellt den meistgenutzten Messengerdienst weltweit dar.<\/li><li><strong>Pinterest<\/strong>: \u00c4hnlich wie Instagram konzentriert sich <a href=\"https:\/\/swat.io\/de\/wiki\/pinterest\/\">Pinterest<\/a> auf visuelle Inhalte. Diese tragen hier den Namen Pins und sind an Pinnw\u00e4nden angeordnet.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Daneben existieren vorwiegend in Asien gro\u00dfe soziale Medien wie WeChat und Sina Weibo, die in der westlichen Welt gar nicht oder kaum bekannt sind.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">M\u00f6glichkeiten der Nutzung<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Social Media werden neben dem Austausch h\u00e4ufig als Informationsquelle verwendet. Unternehmen k\u00f6nnen beides auf vielf\u00e4ltige Weise nutzen. So lassen sich mit den richtigen Inhalten die eigene Reichweite steigern, das Image einer Marke positiv beeinflussen und mehr Besucher auf Webseiten und in Onlineshops bringen. Teilweise k\u00f6nnen soziale Medien direkt f\u00fcr den Verkauf genutzt werden. Au\u00dferdem eignen sie sich f\u00fcr den Kundenservice und zur Recherche relevanter Trends und Entwicklungen.<\/p>\n\n\n\t\t\n\t\t\t<div class=\"wp-block-advice\">\n\t\t\t\t<div class=\"advice__inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"advice__text text text-rich\">\n\t\t\t\t\t\t\n\n<p class=\"wp-block-paragraph\">Ein Social Media Management Tool wie Swat.io erleichtert die Social Media Prozesse von Unternehmen. Jetzt <a href=\"http:\/\/relaunch.swat.io\/de\/demo\" class=\"rank-math-link\">unverbindliche Demo beantragen<\/a> und kostenlos testen!<\/p>\n\n\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\n\t\t\n\n\n<h2 class=\"wp-block-heading\">Quellenangaben<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">[1] vgl. z. B. Schuler, Marcus, <a aria-label=\"Bilanz f\u00fcr 2018. Facebooks gr\u00f6\u00dftes Skandal-Jahr (opens in a new tab)\" rel=\"noreferrer noopener\" href=\"https:\/\/www.tagesschau.de\/wirtschaft\/facebook-jahresbilanz-101.html\" target=\"_blank\">Bilanz f\u00fcr 2018. Facebooks gr\u00f6\u00dftes Skandal-Jahr<\/a>, tagesschau.de, abgerufen am 29.5.2019, Milz, Aniko, Skandal bei Instagram: Daten von diversen Influencern \u00f6ffentlich einsehbar, onlinemarketing.de, abgerufen am 29.5.2019 (Stand: 29.5.2019) und Br\u00fchl, Jannis \/ Brunner, Katharina \/ Ebitsch, Sabrina, <a aria-label=\"Der Facebook-Faktor, Wie das soziale Netzwerk die Wahl beeinflusst (opens in a new tab)\" href=\"https:\/\/gfx.sueddeutsche.de\/apps\/e502288\/www\/\" target=\"_blank\" rel=\"noreferrer noopener\">Der Facebook-Faktor, Wie das soziale Netzwerk die Wahl beeinflusst<\/a>, sueddeutsche.de, abgerufen am 29.5.2019<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"featured_media":27394,"template":"","meta":{"footnotes":""},"swatio_wiki_category":[709],"swatio_wiki_tag":[],"class_list":["entry","entry--swatio_wiki"],"_links":{"self":[{"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/swatio_wiki\/15389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/swatio_wiki"}],"about":[{"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/types\/swatio_wiki"}],"version-history":[{"count":0,"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/swatio_wiki\/15389\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/media\/27394"}],"wp:attachment":[{"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/media?parent=15389"}],"wp:term":[{"taxonomy":"swatio_wiki_category","embeddable":true,"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/swatio_wiki_category?post=15389"},{"taxonomy":"swatio_wiki_tag","embeddable":true,"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/swatio_wiki_tag?post=15389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}