{"id":15635,"date":"2019-12-19T15:00:30","date_gmt":"2019-12-19T15:00:30","guid":{"rendered":"https:\/\/swat.io\/?post_type=swatio_wiki&#038;p=15635"},"modified":"2022-08-10T09:24:56","modified_gmt":"2022-08-10T07:24:56","slug":"snapchat","status":"publish","type":"swatio_wiki","link":"https:\/\/swat.io\/de\/wiki\/snapchat\/","title":{"rendered":"Snapchat"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Snapchat ist ein <strong>kostenloser Instant-Messaging-Dienst<\/strong>, mit dem Nutzer auf mobilen Endger\u00e4ten Bild- und Videonachrichten versenden k\u00f6nnen. Ein besonderes Merkmal der App besteht darin, dass sich Empf\u00e4nger die erhaltenen Bilder oder Videos nur maximal zwei Mal ansehen k\u00f6nnen. Danach l\u00f6schen sich diese selbst. L\u00e4nger vorhanden sind nur <a href=\"https:\/\/swat.io\/de\/wiki\/snapchat-stories\/\">Snapchat Stories<\/a>. Snapchat ist vor allem bei jungen Menschen erfolgreich. Unternehmen nutzen Snapchat f\u00fcr Content Marketing und f\u00fcr <a href=\"https:\/\/swat.io\/de\/wiki\/social-media-werbung\/\">Anzeigenwerbung<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Die Entstehung von Snapchat<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Gegr\u00fcndet wurde Snapchat 2011 von den Entwicklern Evan Spiegel und Robert Murphy. Au\u00dferdem an Idee und Entwicklung beteiligt war Reggie Brown, dem jedoch im Rahmen eines Streits s\u00e4mtliche Beteiligungen an dem Unternehmen abgesprochen wurden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Anfangs konnten User mit Snapchat nur Bilder versenden, Ende 2012 f\u00fchrte der Dienst die Videofunktion ein. 2013 war das Geburtsjahr der Snapchat Stories, die als Vorbild f\u00fcr <a href=\"https:\/\/swat.io\/de\/wiki\/stories\/\">Storyfunktionen in anderen sozialen Netzwerken<\/a> gelten. In den Folgejahren wurde die App um <strong>diverse <a href=\"https:\/\/swat.io\/de\/wiki\/snapchat-filter-linsen\/\">Filter<\/a> und andere Zusatzfunktionen<\/strong> erg\u00e4nzt und konnte ein <strong>stetiges Wachstum<\/strong> verzeichnen. Kaufanfragen von <a href=\"https:\/\/swat.io\/de\/wiki\/facebook\/\">Facebook<\/a> und Google lehnte das Unternehmen, das sich 2016 in Snap Inc. umbenannt hatte, ab.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Besonderheiten von Snapchat<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wie bereits angesprochen, hebt sich Snapchat durch sein \u201c<strong>Verg\u00e4nglichkeitsprinzip<\/strong>\u201d von anderen sozialen Netzwerken ab. Dies bedeutet, dass Empf\u00e4nger von Botschaften (den sogenannten \u201cSnaps\u201d) diese nur zwei Mal, fr\u00fcher sogar nur einmal, ansehen k\u00f6nnen, bevor sie gel\u00f6scht werden. Stories bleiben f\u00fcr 24 Stunden existent. \u00c4hnliches gilt f\u00fcr Textnachrichten, die per Snapchat versendet werden. Wenn der Empf\u00e4nger diese nicht extra speichert, werden sie gel\u00f6scht, sobald er den Chat verlassen hat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Snapchat-Nutzer haben die M\u00f6glichkeit, die von ihnen versendeten Snaps auszuschm\u00fccken, zum Beispiel mit vorgefertigten Bildern, Filtern oder Animationen. Sehr beliebt sind Lenses. Diese scannen Gesichter vor der Kamera und versehen sie automatisch mit Animationen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Besonderheiten kamen von Anfang an <strong>besonders bei einer jungen Nutzerschaft an<\/strong>. Im zweiten Quartal 2019 z\u00e4hlte Snapchat nach eigenen Angaben 203 Millionen aktive Nutzer weltweit. Die meisten davon sind unter 34 Jahre alt. [1]<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dabei stieg die Nutzerzahl von Snapchat nach Verlusten in der j\u00fcngsten Vergangenheit wieder deutlich an. Experten sehen das als Anzeichen daf\u00fcr, dass sich die Plattform nach einem vor\u00fcbergehenden Niedergang erholt und wieder an Bedeutung gewinnt. [2]<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Funktionen von Snapchat<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Snapchat bietet Nutzern die folgenden Funktionen:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Account<\/strong>: Indem Nutzer einen Account bei Snapchat er\u00f6ffnen, bekommen sie einen eigenen Kanal.<\/li><li><strong>Snaps<\/strong>: Im Zentrum von Snapchat stehen die bereits angesprochenen Snaps, also Bilder und Videos, die Nutzer mit der Kamera ihres Mobilger\u00e4ts aufnehmen, bearbeiten und an andere Nutzer in der eigenen Kontaktliste verschicken k\u00f6nnen.<\/li><li><strong>Filter und Linsen<\/strong>: <a href=\"https:\/\/swat.io\/de\/wiki\/snapchat-filter-linsen\/\">Snapchat Filter und Linsen<\/a> stellen die wichtigsten Bearbeitungsm\u00f6glichkeiten von Snaps dar. W\u00e4hrend es sich bei Filter um statische Effekte handelt, sind Linsen bzw. Lenses dynamisch. Zus\u00e4tzlich zu vorgefertigten Varianten haben Snapchat User mittlerweile die M\u00f6glichkeit, selbst Linsen und Filter zu erstellen.<\/li><li><strong>Stories<\/strong>: Bei den Snapchat Stories handelt es sich um Snaps, die zu einer Geschichte zusammengef\u00fcgt und f\u00fcr 24 Stunden im eigenen Kanal pr\u00e4sentiert werden.<\/li><li><strong>Instant-Messaging<\/strong>: \u00c4hnlich wie auf Facebook l\u00e4sst sich \u00fcber Snapchat mit bis zu 16 Personen chatten, mit Text, Snaps oder Sprachnachrichten.<\/li><li><strong>Bitmojis<\/strong>: Bei Bitmojis handelt es sich um pers\u00f6nliche <a href=\"https:\/\/swat.io\/de\/wiki\/emojis\/\">Emojis<\/a> bzw. Avatare, die Nutzer erstellen und mit pers\u00f6nlichen Merkmalen ausstatten k\u00f6nnen.<\/li><li><strong>Snap Games<\/strong>: Relativ neu ist die Option, durch einen Klick auf das betreffende Symbol ein Spiel zu spielen und dabei sogar gegen Freunde anzutreten.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Snapchat im Marketing<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Unternehmen haben zwei grundlegende M\u00f6glichkeiten, <a href=\"https:\/\/swat.io\/de\/wiki\/snapchat-marketing\/\">Snapchat f\u00fcr das Marketing<\/a> zu nutzen:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li><strong>Content Marketing:<\/strong> Unternehmen k\u00f6nnen wie auf anderen Plattformen Inhalte in ihrem Account bzw. Kanal bereitstellen. Nachteilig an Snapchat ist, dass organische Reichweite in dem Netzwerk quasi nicht vorhanden ist. Das bedeutet, dass man Nutzer aktiv in anderen Kan\u00e4len auf die eigene Snapchat-Pr\u00e4senz aufmerksam machen muss. Verbreitet ist au\u00dferdem die Zusammenarbeit mit <a href=\"https:\/\/swat.io\/de\/wiki\/influencer\/\">Influencern<\/a>.<\/li><li><strong>Anzeigenwerbung<\/strong>: Au\u00dferdem bietet Snapchat aktuell f\u00fcnf Anzeigenformate f\u00fcr Werbetreibende: <ul><li><strong>Snap Ads<\/strong>: Diese Fullscreen-Anzeigen erscheinen in Stories.<\/li><li><strong>Collection Ads<\/strong>: Collection Ads funktionieren wie Snap Ads, zeigen aber eine Liste von Produkten am unteren Rand. Nutzer, die darauf klicken, kommen direkt zur jeweiligen Produktseite im Onlineshop.<\/li><li><strong>Story Ads<\/strong>: Story Ads werden auf Snapchat Discover platziert.<\/li><li><strong>Filter<\/strong>: Ebenfalls eine vielversprechende Werbem\u00f6glichkeit stellen eigene (sponsored) Filter dar, mit denen Nutzer Botschaften bearbeiten k\u00f6nnen, indem sie zum Beispiel Grafiken hinzuf\u00fcgen oder Angaben zum Standort machen.<\/li><li><strong>AR-Linsen<\/strong>: Sponsored Lenses eignen sich sehr gut, um mit selbst bzw. von beauftragten Kreativen erstellten Linsen f\u00fcr Events, Marken und Unternehmen zu werben. <\/li><\/ul><\/li><\/ol>\n\n\n\n<h2 class=\"wp-block-heading\">Snapchat Discover<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Snapchat Discover bzw. Entdecken ist in drei Bereiche eingeteilt:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u201c<strong>Freunde<\/strong>\u201d pr\u00e4sentiert die Stories der eigenen Freunde.<\/li><li>Der <strong>Abo-Bereich<\/strong> enth\u00e4lt Shows und Stories, die der jeweilige Nutzer abonniert hat.<\/li><li>\u201c<strong>F\u00fcr Dich<\/strong>\u201d versammelt Empfehlungen, Stories von Herausgebern, Influencern, Snap Stars und der Community sowie gesponserte Stories,<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Teilweise besteht \u00fcber Snapchat Discover auch die M\u00f6glichkeit, Events live zu verfolgen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quellenangaben<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">[1] vgl. z. B. Firsching, Jan, <a rel=\"noreferrer noopener\" aria-label=\"Snapchat Statistiken f\u00fcr 2019: Nutzerzahlen, versendete Snaps &amp; Verweildauer (opens in a new tab)\" href=\"https:\/\/www.omnicoreagency.com\/snapchat-statistics\/ und http:\/\/www.futurebiz.de\/artikel\/snapchat-statistiken-nutzerzahlen\/#.XVqx-Ogzbic\" target=\"_blank\">Snapchat Statistiken f\u00fcr 2019: Nutzerzahlen, versendete Snaps &amp; Verweildauer<\/a>, Futurebiz, abgerufen am 10.11.2019 <br>[2] <a href=\"https:\/\/www.internetworld.de\/social-media\/snapchat\/snapchat-verzeichnet-deutlichen-user-zuwachs-1732095.html\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Snapchat verzeichnet deutlichen User-Zuwachs (opens in a new tab)\">Snapchat verzeichnet deutlichen User-Zuwachs<\/a>, Internet World Business, abgerufen am 10.11.2019<\/p>\n","protected":false},"featured_media":27374,"template":"","meta":{"footnotes":""},"swatio_wiki_category":[715,721],"swatio_wiki_tag":[],"class_list":["entry","entry--swatio_wiki"],"_links":{"self":[{"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/swatio_wiki\/15635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/swatio_wiki"}],"about":[{"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/types\/swatio_wiki"}],"version-history":[{"count":0,"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/swatio_wiki\/15635\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/media\/27374"}],"wp:attachment":[{"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/media?parent=15635"}],"wp:term":[{"taxonomy":"swatio_wiki_category","embeddable":true,"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/swatio_wiki_category?post=15635"},{"taxonomy":"swatio_wiki_tag","embeddable":true,"href":"https:\/\/swat.io\/de\/wp-json\/wp\/v2\/swatio_wiki_tag?post=15635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}